{"id":900,"date":"2010-09-09T14:04:22","date_gmt":"2010-09-09T12:04:22","guid":{"rendered":"http:\/\/www.olympicwings.com\/?p=900"},"modified":"2017-12-10T15:40:37","modified_gmt":"2017-12-10T13:40:37","slug":"livithra-the-historical-city-of-orfeus","status":"publish","type":"post","link":"https:\/\/www.olympicwings.com\/de\/archives\/900","title":{"rendered":"Livithra &#8211; die historische Stadt des Orpheus"},"content":{"rendered":"<p>&nbsp;<\/p>\nngg_shortcode_6_placeholder\n<p>Die Ausgrabungen von Livithra befinden sich am Fuss des Olymps ca. 7 km vom Dorf Leptokaria an der Olympischen Riviera entfernt.<br \/>\nAn der Strasse von Leptokaria nach Karia finden Sie eine Kreuzung mit einem kleinen Kontrollpunkt des Olymp Nationalparks. Rechts geht es nach Palaio (Alt) Leprokaria, Sie biegen nach links ab und folgen den Schildern zum Eingang der Ausgrabungsst\u00e4tte. Einige Stufen f\u00fchren auf den Grund der Schlucht, hier laden riesige Platanen und eine Raststelle zum Verweilen ein. Gegen\u00fcber auf einer Anh\u00f6he befinden sich die Ausgrabungen und in der N\u00e4he die \u00dcberreste eines Friedhofes.<br \/>\nDiese historische Stadt wurde w\u00e4hrend dem 10. Jhd. v.Chr. gebaut und steht in Verbindung mit den Mythen um Orpheus.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h4>Die historische Stadt Livithra<\/h4>\n<p>Leibethra (Libethra) war eine antike makedonische Stadt am Fu\u00df des Berges Olymp, nahe dem heutigen Ort Skotina, mit in der Antike bedeutendem Dionysosheiligtum. Dies l\u00e4sst die Vermutung zu, dass die Einwohner thrakische Wurzeln hatten. Arch\u00e4ologen fanden hier Gr\u00e4ber aus der sp\u00e4ten Bronzezeit (13.-12. Jahrhundert v. Chr.) mit reichen Beigaben.<\/p>\n<p>&nbsp;<\/p>\n<p>Nach der griechischen Mythologie wurde Orpheus hier begraben, andere Quellen berichten jedoch auch, er sei hier geboren oder habe nur vor\u00fcbergehend in Leibethra gelebt. Sprichw\u00f6rtlich galten die Einwohner der Stadt in der Antike als dumm.<\/p>\n<p>&nbsp;<\/p>\n<h4>Die Mythologie des Orpheus<\/h4>\n<p>Orpheus (griechisch \u1f48\u03c1\u03c6\u03b5\u03cd\u03c2) war der ber\u00fchmteste S\u00e4nger in der griechischen Mythologie. Nach ihm wurden die Orphik und der Orphismus benannt.<\/p>\n<p>&nbsp;<\/p>\n<p>Orpheus lebte in Thrakien als Sohn der Muse Kalliope. Sein Vater war der thrakische K\u00f6nig und Flussgott Oiagros (oder, nach anderen \u00dcberlieferungen, Apollon). Von Apollon, dem Gott der Musik, bekam er eine Lyra geschenkt, die Apollon von seinem Halbbruder Hermes erhalten hatte. Unter den S\u00e4ngern galt Orpheus als der Beste. Die B\u00e4ume neigten sich ihm zu, wenn er spielte, und die wilden Tiere scharten sich friedlich um ihn, und selbst die Felsen weinten angesichts seines sch\u00f6nen Gesangs.<\/p>\n<p>&nbsp;<\/p>\n<p>Die Argonauten nahmen ihn auf ihren Kriegsz\u00fcgen mit. Orpheus sang so sch\u00f6n, dass er sogar das w\u00fctende Meer und die Feinde durch den Zauber seiner Lyra bezwang.<\/p>\n<p>&nbsp;<\/p>\n<p>Orpheus\u2019 Ehefrau war die Nymphe Eurydike. Als Aristaios versuchte, sie zu vergewaltigen, und sie vor ihm floh, starb sie durch einen von ihm verschuldeten Schlangenbiss. Orpheus stieg in die Unterwelt, um durch seinen Gesang und das Spiel seiner Lyra den Gott Hades zu bewegen, ihm seine Geliebte zur\u00fcckzugeben. Seine Kunst war so gro\u00df, dass ihm seine Bitte tats\u00e4chlich gew\u00e4hrt wurde &#8211; jedoch unter der von Hades und Persephone gestellten Bedingung, dass er beim Aufstieg in die Oberwelt vorangehen und sich nicht nach ihr umschauen d\u00fcrfe. Da er die Schritte der Eurydike nicht h\u00f6rte, sah er sich um und sie verschwand wieder in der Unterwelt.<\/p>\n<p>&nbsp;<\/p>\n<p>Der S\u00e4nger stand den Musen und somit dem Gott Apollon nahe, nicht aber dem Dionysos, dem Gott des Rausches und ausschweifend-wilder Umz\u00fcge und Ges\u00e4nge. So wurde Orpheus in seiner Heimat von \u201eM\u00e4naden\u201c, berauschten Anh\u00e4ngerinnen des Dionysos, zerrissen. Nach antiker Vorstellung war es kein Trost, dass er nun als Schatten sich zum Schatten der Eurydike gesellen konnte. In sp\u00e4teren Bearbeitungen des Mythos wird als Motiv f\u00fcr den Mord angef\u00fchrt, Orpheus habe sich von der Liebe zu Frauen losgesagt und zum Weiberfeind entwickelt oder sich gar der Knabenliebe zugewandt.<\/p>\n<p>&nbsp;<\/p>\n<p>Sein Kopf jedoch wurde mitsamt seiner Lyra in den Fluss Hebros geworfen, sie schwammen hinab in das \u00c4g\u00e4ische Meer und wurden auf der Insel Lesbos an Land gesp\u00fclt. Der Kopf sang immer weiter, bis Apollon ihm gebot zu schweigen. Sein Grab soll sich in der Stadt Leibethra befunden haben &#8211; andere Quellen nennen diese Stadt auch als Geburtsort des Orpheus und den Fluss, in dem sein Kopf gefunden wurde, Meletos. Seine Lyra wurde als Sternbild an den Himmel gesetzt.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-de\">Leider ist der Eintrag nur auf <a href=\"https:\/\/www.olympicwings.com\/en\/wp-json\/wp\/v2\/posts\/900\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a> verf\u00fcgbar.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[63,64,16,11,12],"tags":[139,141,220,134,140,106,93,102,132,227,66,212,138,133,87,213,135,214,67,128],"class_list":["post-900","post","type-post","status-publish","format-standard","hentry","category-excavations","category-macedonia","category-mount-olympus-regions","category-regions","category-sightseeing","tag-calliope","tag-eurydice","tag-excavations","tag-greek-mythology","tag-hermes","tag-hiking-trekking","tag-holiday","tag-kato-olympos","tag-leptokaria","tag-livithra","tag-macedonian-culture","tag-mount-olympus","tag-muses","tag-national-park","tag-northern-greece","tag-olympic-riviera","tag-orpheus","tag-sightseeing","tag-tomb","tag-tradition"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"(English)\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"claudia k\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.olympicwings.com\/de\/archives\/900\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Hellas Holidays - special holidays in Greece\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Livithra \u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings\" \/>\n\t\t<meta property=\"og:description\" content=\"(English)\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.olympicwings.com\/de\/archives\/900\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2010-09-09T12:04:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2017-12-10T13:40:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Livithra \u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings\" \/>\n\t\t<meta name=\"twitter:description\" content=\"(English)\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#article\",\"name\":\"Livithra \\u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings\",\"headline\":\"Livithra &#8211; die historische Stadt des Orpheus\",\"author\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/author\\\/claudia#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/#organization\"},\"datePublished\":\"2010-09-09T14:04:22+02:00\",\"dateModified\":\"2017-12-10T15:40:37+02:00\",\"inLanguage\":\"de-DE\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#webpage\"},\"articleSection\":\"Ausgrabungen, Makedonien, Olympgebirge, Regionen, Besichtigungen, Kalliope, Eurydike, Ausgrabungen, Griechische Mythologie, Hermes, Wandern &amp; Bergsteigen, Urlaub, Kato Olympos, Leptokaria, Livithra, Makedonische Kultur, Olympgebirge, Musen, Nationalpark, Nordgriechenland, Olympische Riviera, Orpheas, Besichtigungen, Grabst\\u00e4tte, Tradition\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de#listItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/www.olympicwings.com\\\/de\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions#listItem\",\"name\":\"Regionen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions#listItem\",\"position\":2,\"name\":\"Regionen\",\"item\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions\\\/mount-olympus-regions#listItem\",\"name\":\"Olympgebirge\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de#listItem\",\"name\":\"Start\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions\\\/mount-olympus-regions#listItem\",\"position\":3,\"name\":\"Olympgebirge\",\"item\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions\\\/mount-olympus-regions\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#listItem\",\"name\":\"Livithra &#8211; die historische Stadt des Orpheus\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions#listItem\",\"name\":\"Regionen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#listItem\",\"position\":4,\"name\":\"Livithra &#8211; die historische Stadt des Orpheus\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/category\\\/regions\\\/mount-olympus-regions#listItem\",\"name\":\"Olympgebirge\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/#organization\",\"name\":\"Hellas Holidays\",\"description\":\"special holidays in Greece\",\"url\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/author\\\/claudia#author\",\"url\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/author\\\/claudia\",\"name\":\"claudia k\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78770c679a6296d5f958165cc229e1fc49a9287aba08c8a9934824afd85ec2b5?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"claudia k\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#webpage\",\"url\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900\",\"name\":\"Livithra \\u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings\",\"description\":\"(English)\",\"inLanguage\":\"de-DE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/900#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/author\\\/claudia#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/archives\\\/author\\\/claudia#author\"},\"datePublished\":\"2010-09-09T14:04:22+02:00\",\"dateModified\":\"2017-12-10T15:40:37+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/\",\"name\":\"Hellas Holidays\",\"description\":\"special holidays in Greece\",\"inLanguage\":\"de-DE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.olympicwings.com\\\/de\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Livithra \u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings","description":"(English)","canonical_url":"https:\/\/www.olympicwings.com\/de\/archives\/900","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#article","name":"Livithra \u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings","headline":"Livithra &#8211; die historische Stadt des Orpheus","author":{"@id":"https:\/\/www.olympicwings.com\/de\/archives\/author\/claudia#author"},"publisher":{"@id":"https:\/\/www.olympicwings.com\/de\/#organization"},"datePublished":"2010-09-09T14:04:22+02:00","dateModified":"2017-12-10T15:40:37+02:00","inLanguage":"de-DE","mainEntityOfPage":{"@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#webpage"},"isPartOf":{"@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#webpage"},"articleSection":"Ausgrabungen, Makedonien, Olympgebirge, Regionen, Besichtigungen, Kalliope, Eurydike, Ausgrabungen, Griechische Mythologie, Hermes, Wandern &amp; Bergsteigen, Urlaub, Kato Olympos, Leptokaria, Livithra, Makedonische Kultur, Olympgebirge, Musen, Nationalpark, Nordgriechenland, Olympische Riviera, Orpheas, Besichtigungen, Grabst\u00e4tte, Tradition"},{"@type":"BreadcrumbList","@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de#listItem","position":1,"name":"Start","item":"https:\/\/www.olympicwings.com\/de","nextItem":{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions#listItem","name":"Regionen"}},{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions#listItem","position":2,"name":"Regionen","item":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions","nextItem":{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions\/mount-olympus-regions#listItem","name":"Olympgebirge"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de#listItem","name":"Start"}},{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions\/mount-olympus-regions#listItem","position":3,"name":"Olympgebirge","item":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions\/mount-olympus-regions","nextItem":{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#listItem","name":"Livithra &#8211; die historische Stadt des Orpheus"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions#listItem","name":"Regionen"}},{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#listItem","position":4,"name":"Livithra &#8211; die historische Stadt des Orpheus","previousItem":{"@type":"ListItem","@id":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions\/mount-olympus-regions#listItem","name":"Olympgebirge"}}]},{"@type":"Organization","@id":"https:\/\/www.olympicwings.com\/de\/#organization","name":"Hellas Holidays","description":"special holidays in Greece","url":"https:\/\/www.olympicwings.com\/de\/"},{"@type":"Person","@id":"https:\/\/www.olympicwings.com\/de\/archives\/author\/claudia#author","url":"https:\/\/www.olympicwings.com\/de\/archives\/author\/claudia","name":"claudia k","image":{"@type":"ImageObject","@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/78770c679a6296d5f958165cc229e1fc49a9287aba08c8a9934824afd85ec2b5?s=96&d=mm&r=g","width":96,"height":96,"caption":"claudia k"}},{"@type":"WebPage","@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#webpage","url":"https:\/\/www.olympicwings.com\/de\/archives\/900","name":"Livithra \u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings","description":"(English)","inLanguage":"de-DE","isPartOf":{"@id":"https:\/\/www.olympicwings.com\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.olympicwings.com\/de\/archives\/900#breadcrumblist"},"author":{"@id":"https:\/\/www.olympicwings.com\/de\/archives\/author\/claudia#author"},"creator":{"@id":"https:\/\/www.olympicwings.com\/de\/archives\/author\/claudia#author"},"datePublished":"2010-09-09T14:04:22+02:00","dateModified":"2017-12-10T15:40:37+02:00"},{"@type":"WebSite","@id":"https:\/\/www.olympicwings.com\/de\/#website","url":"https:\/\/www.olympicwings.com\/de\/","name":"Hellas Holidays","description":"special holidays in Greece","inLanguage":"de-DE","publisher":{"@id":"https:\/\/www.olympicwings.com\/de\/#organization"}}]},"og:locale":"de_DE","og:site_name":"Hellas Holidays - special holidays in Greece","og:type":"article","og:title":"Livithra \u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings","og:description":"(English)","og:url":"https:\/\/www.olympicwings.com\/de\/archives\/900","article:published_time":"2010-09-09T12:04:22+00:00","article:modified_time":"2017-12-10T13:40:37+00:00","twitter:card":"summary_large_image","twitter:title":"Livithra \u2013 die historische Stadt des Orpheus | Hellas Holidays by Olympic Wings","twitter:description":"(English)"},"aioseo_meta_data":{"post_id":"900","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-18 16:49:53","updated":"2025-06-03 19:48:49","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.olympicwings.com\/de\" title=\"Start\">Start<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions\" title=\"Regionen\">Regionen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions\/mount-olympus-regions\" title=\"Olympgebirge\">Olympgebirge<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLivithra \u2013 die historische Stadt des Orpheus\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Start","link":"https:\/\/www.olympicwings.com\/de"},{"label":"Regionen","link":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions"},{"label":"Olympgebirge","link":"https:\/\/www.olympicwings.com\/de\/archives\/category\/regions\/mount-olympus-regions"},{"label":"Livithra &#8211; die historische Stadt des Orpheus","link":"https:\/\/www.olympicwings.com\/de\/archives\/900"}],"_links":{"self":[{"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/posts\/900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/comments?post=900"}],"version-history":[{"count":0,"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/posts\/900\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/media?parent=900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/categories?post=900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.olympicwings.com\/de\/wp-json\/wp\/v2\/tags?post=900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}